{"id":126837,"date":"2022-08-10T08:29:30","date_gmt":"2022-08-10T13:29:30","guid":{"rendered":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1958-12-neckerchief-slide-of-the-month-little-eskimo-8\/"},"modified":"2023-01-17T01:05:10","modified_gmt":"2023-01-17T01:05:10","slug":"boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim","status":"publish","type":"page","link":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/","title":{"rendered":"Boy&#8217;s Life &#8211; 1960-07 &#8211; Neckerchief Ole&#8217; Man of Hawaii &#8211; Whittlin Jim"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Boy&#8217;s Life &#8211; 1960-07 &#8211; Neckerchief Ole&#8217; Man of Hawaii &#8211; Whittlin Jim<\/mark><\/p>\n\n\n\n<center><d3><a style=\"color:Tomato;\" href=\"https:\/\/www.snapwhole.com\/index.php\/boys-life-magazine-neckerchief-slide-articles\/\">Return to Boy&#8217;s Life Magazine Neckerchief Slide Articles<\/a><\/d3><\/center><br><br>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"263\" height=\"587\" src=\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg\" alt=\"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim\" class=\"wp-image-126800\" srcset=\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg 263w, https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead-134x300.jpg 134w\" sizes=\"(max-width: 263px) 100vw, 263px\" \/><\/a><figcaption>Boy&#8217;s Life &#8211; 1960-07 &#8211; Neckerchief Ole&#8217; Man of Hawaii &#8211; Whittlin Jim<\/figcaption><\/figure><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p>Whittlin Jim is an alternate author name for Ben Hunt<\/p>\n\n\n\n<p>A relative easy slide<\/p>\n\n\n\n<p>A good looking slide<\/p>\n\n\n\n<p>detail can be added with a knife or with paint<\/p>\n\n\n\n<p>Same basic mask shape can be used for other slides, like african faces<\/p>\n\n\n\n<p>W Ben Hunt created the Whittlin Jim and Lone Eagle names, and published articles under all three name &#8211; Ben Hunt wrote 2-4 articles per month for Boy&#8217;s Life, and I think he created the Whittlin Jim and Lone Eagle to make is seem like there were multiple authors writing the articles<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color\">Full Article<\/p>\n\n\n<div id=\"wppdfemb-frame-container-126801\"><iframe id=\"wppdf-emb-iframe-126801\" scrolling=\"no\" data-pdf-index=\"2\" class=\"pdfembed-iframe nonfullscreen\" style=\"border: none; width:100%; max-width: 100%; min-height: 1000px;\" src=\"https:\/\/www.snapwhole.com?pdfID=126801&#038;url=%2F%3Fpdfemb-serveurl%3Dhttps%253A%252F%252Fwww.snapwhole.com%252Fwp-content%252Fuploads%252Fsecurepdfs%252F2022%252F08%252FBoys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-middle.pdf%26pdfemb-nonce%3D5becbf4ede&#038;index=2\" ><\/iframe><\/div>\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color\">Full Page<\/p>\n\n\n<div id=\"wppdfemb-frame-container-126799\"><iframe id=\"wppdf-emb-iframe-126799\" scrolling=\"no\" data-pdf-index=\"3\" class=\"pdfembed-iframe nonfullscreen\" style=\"border: none; width:100%; max-width: 100%; min-height: 1000px;\" src=\"https:\/\/www.snapwhole.com?pdfID=126799&#038;url=%2F%3Fpdfemb-serveurl%3Dhttps%253A%252F%252Fwww.snapwhole.com%252Fwp-content%252Fuploads%252Fsecurepdfs%252F2022%252F08%252FBoys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole.pdf%26pdfemb-nonce%3D8ed0f08798&#038;index=3\" ><\/iframe><\/div>\n\n\n<p class=\"has-text-align-center\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Boy&#8217;s Life &#8211; 1960-07 &#8211; Neckerchief Ole&#8217; Man of Hawaii &#8211; Whittlin Jim<\/mark><\/p>\n\n\n\n<center><d3><a style=\"color:Tomato;\" href=\"https:\/\/www.snapwhole.com\/index.php\/boys-life-magazine-neckerchief-slide-articles\/\">Return to Boy&#8217;s Life Magazine Neckerchief Slide Articles<\/a><\/d3><\/center><br><br>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_126837\" class=\"pvc_stats all  \" data-element-id=\"126837\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.snapwhole.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Boy&#8217;s Life &#8211; 1960-07 &#8211; Neckerchief Ole&#8217; Man of Hawaii &#8211; Whittlin Jim Return to Boy&#8217;s Life Magazine Neckerchief Slide Articles Whittlin Jim is an alternate author name for Ben Hunt A relative easy slide A good looking slide detail can be added with a knife or with paint Same basic mask shape can be [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_126837\" class=\"pvc_stats all  \" data-element-id=\"126837\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.snapwhole.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"a3_pvc":{"activated":true,"total_views":100,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boy&#039;s Life - 1960-07 - Neckerchief Ole&#039; Man of Hawaii - Whittlin Jim - SnapWhole.com<\/title>\n<meta name=\"description\" content=\"Boy&#039;s Life - 1960-07 - Neckerchief Ole&#039; Man of Hawaii - Whittlin Jim\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boy&#039;s Life - 1960-07 - Neckerchief Ole&#039; Man of Hawaii - Whittlin Jim - SnapWhole.com\" \/>\n<meta property=\"og:description\" content=\"Boy&#039;s Life - 1960-07 - Neckerchief Ole&#039; Man of Hawaii - Whittlin Jim\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/\" \/>\n<meta property=\"og:site_name\" content=\"SnapWhole.com\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-17T01:05:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/\",\"url\":\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/\",\"name\":\"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim - SnapWhole.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.snapwhole.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg\",\"datePublished\":\"2022-08-10T13:29:30+00:00\",\"dateModified\":\"2023-01-17T01:05:10+00:00\",\"description\":\"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim\",\"breadcrumb\":{\"@id\":\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#primaryimage\",\"url\":\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg\",\"contentUrl\":\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg\",\"width\":263,\"height\":587,\"caption\":\"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.snapwhole.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boy&#8217;s Life &#8211; 1960-07 &#8211; Neckerchief Ole&#8217; Man of Hawaii &#8211; Whittlin Jim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.snapwhole.com\/#website\",\"url\":\"https:\/\/www.snapwhole.com\/\",\"name\":\"SnapWhole.com\",\"description\":\"Your Cool Refreshing Eclectic Destination\",\"publisher\":{\"@id\":\"https:\/\/www.snapwhole.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.snapwhole.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.snapwhole.com\/#organization\",\"name\":\"Snapwhole\",\"url\":\"https:\/\/www.snapwhole.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.snapwhole.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2021\/04\/radioactive.jpg\",\"contentUrl\":\"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2021\/04\/radioactive.jpg\",\"width\":282,\"height\":268,\"caption\":\"Snapwhole\"},\"image\":{\"@id\":\"https:\/\/www.snapwhole.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim - SnapWhole.com","description":"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/","og_locale":"en_US","og_type":"article","og_title":"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim - SnapWhole.com","og_description":"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim","og_url":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/","og_site_name":"SnapWhole.com","article_modified_time":"2023-01-17T01:05:10+00:00","og_image":[{"url":"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/","url":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/","name":"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim - SnapWhole.com","isPartOf":{"@id":"https:\/\/www.snapwhole.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#primaryimage"},"image":{"@id":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg","datePublished":"2022-08-10T13:29:30+00:00","dateModified":"2023-01-17T01:05:10+00:00","description":"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim","breadcrumb":{"@id":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#primaryimage","url":"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg","contentUrl":"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2022\/08\/Boys-Life-1960-07-Neckerchief-Ole-Man-of-Hawaii-Whittlin-Jim-snapwhole-lead.jpg","width":263,"height":587,"caption":"Boy's Life - 1960-07 - Neckerchief Ole' Man of Hawaii - Whittlin Jim"},{"@type":"BreadcrumbList","@id":"https:\/\/www.snapwhole.com\/index.php\/boys-life-1960-07-neckerchief-ole-man-of-hawaii-whittlin-jim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.snapwhole.com\/"},{"@type":"ListItem","position":2,"name":"Boy&#8217;s Life &#8211; 1960-07 &#8211; Neckerchief Ole&#8217; Man of Hawaii &#8211; Whittlin Jim"}]},{"@type":"WebSite","@id":"https:\/\/www.snapwhole.com\/#website","url":"https:\/\/www.snapwhole.com\/","name":"SnapWhole.com","description":"Your Cool Refreshing Eclectic Destination","publisher":{"@id":"https:\/\/www.snapwhole.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.snapwhole.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.snapwhole.com\/#organization","name":"Snapwhole","url":"https:\/\/www.snapwhole.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.snapwhole.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2021\/04\/radioactive.jpg","contentUrl":"https:\/\/www.snapwhole.com\/wp-content\/uploads\/2021\/04\/radioactive.jpg","width":282,"height":268,"caption":"Snapwhole"},"image":{"@id":"https:\/\/www.snapwhole.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.snapwhole.com\/index.php\/wp-json\/wp\/v2\/pages\/126837"}],"collection":[{"href":"https:\/\/www.snapwhole.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.snapwhole.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.snapwhole.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snapwhole.com\/index.php\/wp-json\/wp\/v2\/comments?post=126837"}],"version-history":[{"count":3,"href":"https:\/\/www.snapwhole.com\/index.php\/wp-json\/wp\/v2\/pages\/126837\/revisions"}],"predecessor-version":[{"id":126866,"href":"https:\/\/www.snapwhole.com\/index.php\/wp-json\/wp\/v2\/pages\/126837\/revisions\/126866"}],"wp:attachment":[{"href":"https:\/\/www.snapwhole.com\/index.php\/wp-json\/wp\/v2\/media?parent=126837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}